{"id":3598,"date":"2019-03-23T00:19:36","date_gmt":"2019-03-22T23:19:36","guid":{"rendered":"https:\/\/2019.bordeaux.wordcamp.org\/?p=3598"},"modified":"2019-03-23T00:19:36","modified_gmt":"2019-03-22T23:19:36","slug":"se-rendre-a-la-soiree-de-cloture","status":"publish","type":"post","link":"https:\/\/bordeaux.wordcamp.org\/2019\/se-rendre-a-la-soiree-de-cloture\/","title":{"rendered":"Se rendre \u00e0 la soir\u00e9e de cl\u00f4ture"},"content":{"rendered":"<div class=\"googlemaps\">\n\t\t\t\t<iframe loading=\"lazy\" width=\"640\" height=\"480\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"  src=\"https:\/\/www.google.fr\/maps\/d\/embed?mid=1b0wAM1k1uORWk49bp6areyb4fKUXTnPe\"><\/iframe>\n\t\t\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le Magasin g\u00e9n\u00e9ral se situe sur la rive droite bordelaise. Pour vous y rendre, plusieurs possibilit\u00e9s :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En tram<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Prenez <strong>le tram B \u00e0 l\u2019arr\u00eat CAPC<\/strong>, juste devant la Cit\u00e9 Mondiale \u2013 qui accueille la journ\u00e9e de conf\u00e9rences, puis <strong>descendez \u00e0 l\u2019arr\u00eat Quinconces pour prendre la ligne B, direction Porte de Bourgogne<\/strong>.\n Vous pouvez aussi tout simplement vous rendre \u00e0 pied vers la place des \nQuinconces ou la place de la Bourse pour r\u00e9cup\u00e9rer le tram B, histoire \nde profiter de la vue :).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00e0, grimpez dans le <strong>tram A pour vous arr\u00eater \u00e0 l\u2019arr\u00eat Stalingrad<\/strong>,\n ou traversez le pont de pierre \u00e0 pied pour profiter, l\u00e0 encore,de la \njolie vue qu\u2019il propose sur la ville. Parvenu\u00b7e rive droite, Il vous \nfaudra marcher une dizaine de minutes suppl\u00e9mentaires, le long de la \nGaronne \u2013 qui vous propose \u00e9galement une tr\u00e8s belle vue sur la ville, \navant d\u2019arriver \u00e0 DARWIN, qui abrite le Magasin g\u00e9n\u00e9ral.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En bateau<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Marchez le long du quai en direction de la place des Quinquonces, sur laquelle vous pourrez acc\u00e9der au <strong>Bat<sup>3<\/sup>, la navette fluviale permettant de traverser la Garonne d\u2019une rive \u00e0 l\u2019autre<\/strong>.\n Elle vous d\u00e9posera au pied de la place Stalingrad, de laquelle vous \npourrez partir pour longer la rive jusqu\u2019\u00e0 l\u2019\u00e9co-syst\u00e8me DARWIN.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En v\u00e9lo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une station de v\u00e9lo V<sup>3<\/sup> se situe \u00e0 deux pas de la Cit\u00e9 \nMondiale, vous pourrez ainsi longer la Garonne en direction du pont de \npierre, puis remonter celle-ci jusqu\u2019\u00e0 DARWIN, o\u00f9 vous trouverez une \nstation pour garer votre v\u00e9lo le temps de la soir\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"520\" src=\"https:\/\/2019.bordeaux.wordcamp.org\/files\/2019\/02\/soiree-cloture-wcbdx-2019-01-800x520.jpg\" alt=\"Foodtruck du Magasin g\u00e9n\u00e9ral, Darwin \u00e9co-syst\u00e8me\" class=\"wp-image-3280\" srcset=\"https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/02\/soiree-cloture-wcbdx-2019-01-800x520.jpg 800w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/02\/soiree-cloture-wcbdx-2019-01-300x195.jpg 300w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/02\/soiree-cloture-wcbdx-2019-01-768x500.jpg 768w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/02\/soiree-cloture-wcbdx-2019-01-461x300.jpg 461w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/02\/soiree-cloture-wcbdx-2019-01.jpg 1230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Soir\u00e9e de cl\u00f4ture,<br>WordCamp Bordeaux 2019<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Magasin G\u00e9n\u00e9ral \u2013 Darwin \u00e9cosyst\u00e8me,<br>87 quai des Queyries \u2013 33&nbsp;000 Bordeaux<br><em>\u00e0 partir de 19H<\/em><br><a href=\"https:\/\/magasingeneral.camp\" target=\"_blank\" rel=\"noreferrer noopener\">magasingeneral.camp<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Magasin g\u00e9n\u00e9ral se situe sur la rive droite bordelaise. Pour vous y rendre, plusieurs possibilit\u00e9s : En tram Prenez le tram B \u00e0 l\u2019arr\u00eat CAPC, juste devant la Cit\u00e9 Mondiale \u2013 qui accueille la journ\u00e9e de conf\u00e9rences, puis descendez \u00e0 l\u2019arr\u00eat Quinconces pour prendre la ligne B, direction Porte de Bourgogne. Vous pouvez aussi [&hellip;]<\/p>\n","protected":false},"author":13107811,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3598","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheJKp-W2","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/3598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/users\/13107811"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/comments?post=3598"}],"version-history":[{"count":5,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/3598\/revisions"}],"predecessor-version":[{"id":3603,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/3598\/revisions\/3603"}],"wp:attachment":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=3598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/categories?post=3598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/tags?post=3598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}