{"id":3678,"date":"2019-05-16T14:37:35","date_gmt":"2019-05-16T12:37:35","guid":{"rendered":"https:\/\/2019.bordeaux.wordcamp.org\/?p=3678"},"modified":"2019-05-16T14:47:09","modified_gmt":"2019-05-16T12:47:09","slug":"retour-photos-wordcamp-bordeaux-2019","status":"publish","type":"post","link":"https:\/\/bordeaux.wordcamp.org\/2019\/retour-photos-wordcamp-bordeaux-2019\/","title":{"rendered":"Retour en photos sur le WordCamp Bordeaux 2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Terminons cette \u00e9dition 2019 du WordCamp Bordeaux en se rem\u00e9morant quelques souvenirs captur\u00e9s au vol par notre ami R\u00e9mi Corson au cours de cette folle journ\u00e9e sur <a href=\"https:\/\/flic.kr\/s\/aHsmCtFXvA\">Flickr<\/a>. Le travail de post-traitement a \u00e9t\u00e9 r\u00e9alis\u00e9 par votre humble serviteur. Les photos peuvent \u00eatre t\u00e9l\u00e9charg\u00e9es pour un usage personnel.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/flic.kr\/s\/aHsmCtFXvA\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/2019.bordeaux.wordcamp.org\/files\/2019\/04\/47509210871_399f83e873_k-800x533.jpg\" alt=\"\" class=\"wp-image-3666\" srcset=\"https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/04\/47509210871_399f83e873_k-800x533.jpg 800w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/04\/47509210871_399f83e873_k-300x200.jpg 300w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/04\/47509210871_399f83e873_k-768x512.jpg 768w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/04\/47509210871_399f83e873_k-450x300.jpg 450w, https:\/\/bordeaux.wordcamp.org\/2019\/files\/2019\/04\/47509210871_399f83e873_k.jpg 2048w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pourrez revivre la journ\u00e9e en 2 mn avec la vid\u00e9o ci-dessous.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/an6zgABXBVY?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Terminons cette \u00e9dition 2019 du WordCamp Bordeaux en se rem\u00e9morant quelques souvenirs captur\u00e9s au vol par notre ami R\u00e9mi Corson au cours de cette folle journ\u00e9e sur Flickr. Le travail de post-traitement a \u00e9t\u00e9 r\u00e9alis\u00e9 par votre humble serviteur. Les photos peuvent \u00eatre t\u00e9l\u00e9charg\u00e9es pour un usage personnel. Vous pourrez revivre la journ\u00e9e en 2 [&hellip;]<\/p>\n","protected":false},"author":388646,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3678","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheJKp-Xk","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/3678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/users\/388646"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/comments?post=3678"}],"version-history":[{"count":7,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/3678\/revisions"}],"predecessor-version":[{"id":3691,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/3678\/revisions\/3691"}],"wp:attachment":[{"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=3678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/categories?post=3678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux.wordcamp.org\/2019\/wp-json\/wp\/v2\/tags?post=3678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}